{"id":15,"date":"2022-12-15T15:55:44","date_gmt":"2022-12-15T15:55:44","guid":{"rendered":"https:\/\/labrasserie.es\/?page_id=15"},"modified":"2022-12-15T15:55:44","modified_gmt":"2022-12-15T15:55:44","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/labrasserie.es\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading source=\u00bbpost_title\u00bb use_theme_fonts=\u00bbyes\u00bb]<\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>ENTIDAD: REVYROD, S.L.<\/p>\n<p>\u200bC.I.F : B38421525<\/p>\n<p>\u200bC\/Infanta Elena 16 \u2013 Poligono Industrial Cho \u2013 38632 \u2013 Arona \u2013 Santa Cruz de Tenerife<\/p>\n<p>gourmetlandtfe@gmail.com\/info@gourmetland.net<\/p>\n<p>+34 922 79 84 89<\/p>\n<p>\u200b<\/p>\n<p><strong>1. Objeto y aceptaci\u00f3n<\/strong><\/p>\n<p>\u200b<\/p>\n<p>El presente aviso legal regula el uso del sitio Web:\u00a0<a>www.gourmetland.net.<\/a>\u00a0La navegaci\u00f3n por la p\u00e1gina\u00a0<a href=\"https:\/\/www.gourmetland.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.gourmetland.net<\/a>\u00a0atribuye la condici\u00f3n de usuario de la misma e implica la aceptaci\u00f3n plena y sin reservas de todas y cada una de las disposiciones incluidas en este Aviso Legal, que pueden sufrir modificaciones. El usuario se obliga a hacer un uso correcto del sitio Web de conformidad con las leyes, la buena fe, el orden p\u00fablico, los usos del tr\u00e1fico y el presente Aviso Legal. El Usuario responder\u00e1 frente a REVYROD y frente a terceros, de los da\u00f1os y perjuicios que pudieran causarse como consecuencia del incumplimiento de dicha obligaci\u00f3n.<\/p>\n<p>\u200b<\/p>\n<p><strong>2. Condiciones de acceso y utilizaci\u00f3n<\/strong><\/p>\n<p>\u200b<\/p>\n<p>El sitio Web y sus servicios son de acceso libre y gratuito. El Usuario garantiza la autenticidad y actualidad de todos aquellos datos que comunique a REVYROD y ser\u00e1 el \u00fanico responsable de las manifestaciones falsas o inexactas que realice. El Usuario se compromete expresamente a hacer un uso adecuado de los contenidos y servicios ofrecidos y a no emplearlos para: a) Difundir contenidos delictivos, violentos, pornogr\u00e1ficos, racistas, xen\u00f3fobo, ofensivos, de apolog\u00eda del terrorismo o, en general, contrarios a la ley o al orden p\u00fablico. b) Introducir en la red virus inform\u00e1ticos o realizar actuaciones susceptibles de alterar, estropear, interrumpir o generar errores o da\u00f1os en los documentos electr\u00f3nicos, datos o sistemas f\u00edsicos y l\u00f3gicos de REVYROD o de terceras personas; as\u00ed como obstaculizar el acceso de otros Usuarios al sitio Web y a sus servicios. c) Intentar acceder a \u00e1reas restringidas de los sistemas inform\u00e1ticos de REVYROD o de terceros y, en su caso, extraer informaci\u00f3n. d) Vulnerar los derechos de propiedad intelectual o industrial, as\u00ed como violar la confidencialidad de la informaci\u00f3n de REVYROD o de terceros. e) Suplantar la identidad de otro Usuario, de las administraciones p\u00fablicas o de un tercero. f) Reproducir, copiar, distribuir, poner a disposici\u00f3n o de cualquier otra forma comunicar p\u00fablicamente, transformar o modificar los Contenidos, a menos que se cuente con la autorizaci\u00f3n del titular de los correspondientes derechos o ello resulte legalmente permitido g) Recabar datos con finalidad publicitaria y de remitir publicidad de cualquier clase y comunicaciones con fines de venta u otras de naturaleza comercial sin que medie su previa solicitud o consentimiento. Todos los contenidos del sitio Web, como textos, fotograf\u00edas, gr\u00e1ficos, im\u00e1genes, iconos, tecnolog\u00eda, software, as\u00ed como su dise\u00f1o gr\u00e1fico y c\u00f3digos fuente, constituyen una obra cuya propiedad pertenece a REVYROD, sin que puedan entenderse cedidos al Usuario ninguno de los derechos de explotaci\u00f3n sobre los mismos m\u00e1s all\u00e1 de lo estrictamente necesario para el correcto uso de la Web. En definitiva, los usuarios que accedan a este sitio Web pueden visualizar los contenidos y efectuar, en su caso, copias privadas autorizadas siempre que los elementos reproducidos no sean cedidos posteriormente a terceros, ni se instalen a servidores conectados a redes, ni sean objeto de ning\u00fan tipo de explotaci\u00f3n. As\u00ed mismo, todas las marcas, nombres o signos distintivos de cualquier clase que aparecen en el sitio Web son propiedad de REVYROD, sin que pueda entenderse que el uso o acceso al mismo atribuya al Usuario derecho alguno sobre los mismos. Quedan prohibidas la distribuci\u00f3n, modificaci\u00f3n, cesi\u00f3n o comunicaci\u00f3n p\u00fablica de los contenidos y cualquier otro acto que no haya sido expresamente autorizado por el titular de los derechos de explotaci\u00f3n.<\/p>\n<p>\u200b<\/p>\n<p><strong>3. Pol\u00edtica de privacidad<\/strong><\/p>\n<p>\u200b<\/p>\n<p>Cuando precisemos obtener informaci\u00f3n por su parte, siempre le solicitaremos que nos la proporcione voluntariamente de forma expresa a trav\u00e9s de los formularios de recogida de datos existentes en la Web. En el caso de que el usuario facilite datos de car\u00e1cter personal de personas distintas al usuario se compromete a informar previamente, a las personas de las cuales facilita los datos personales, del contenido de la presente pol\u00edtica de protecci\u00f3n de datos, facilitando a los mismos, si fuera necesario, copia impresa de la misma. Igualmente, cuando los datos se refieran a un menor de edad y sean proporcionados por el mismo, REVYROD supondr\u00e1 que \u00e9l mismo cuenta con el consentimiento de los tutores legales, quedando exenta de cualquier responsabilidad por el incumplimiento de este requisito. De conformidad con lo dispuesto en el art. 4 de la LOPD, el usuario se compromete a facilitar datos verdaderos, exactos, completos y actualizados, de forma que sean veraces y respondan a la situaci\u00f3n real del usuario. Los datos recabados a trav\u00e9s de los formularios y del correo electr\u00f3nico que usted nos remita solicitando informaci\u00f3n sobre nuestros servicios ser\u00e1n incorporados a un fichero automatizado de datos de car\u00e1cter personal con el nombre de \u201cUSUARIOS WEB\u201d del cual es responsable REVYROD que tratar\u00e1 los datos de forma confidencial y exclusivamente con la finalidad de ofrecer los servicios solicitados y la remisi\u00f3n de informaci\u00f3n de nuestros servicios y proyectos, con todas las garant\u00edas legales y de seguridad que impone con todas las garant\u00edas legales y de seguridad que impone el Reglamento (UE) 2016\/679 de Protecci\u00f3n de Datos RGPD, la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y Garant\u00eda de los Derechos Digitales y la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico.<\/p>\n<p>\u200b<\/p>\n<p><strong>Finalidad \u00bfCon qu\u00e9 finalidades tratamos sus datos?<\/strong><\/p>\n<p>\u200b<\/p>\n<p>REVYROD informa al Usuario de la existencia de un tratamiento de datos de car\u00e1cter personal creado con los datos obtenidos en la p\u00e1gina web por y para REVYROD y bajo su responsabilidad.<\/p>\n<p>Dicho fichero ha sido creado con la finalidad de facilitar informaci\u00f3n sobre la prestaci\u00f3n de los servicios ofrecidos por el Portal.<\/p>\n<p>\u200b<\/p>\n<p><strong>Plazos \u00bfpor cu\u00e1nto tiempo conservaremos sus datos personales?<\/strong><\/p>\n<p>\u200b<\/p>\n<p>Los datos personales proporcionados se conservar\u00e1n por el plazo determinado en base los siguientes criterios: (I) obligaci\u00f3n legal de conservaci\u00f3n; (II) duraci\u00f3n de la relaci\u00f3n contractual y atenci\u00f3n de cualesquiera responsabilidades derivadas de dicha relaci\u00f3n; y, (III) solicitud de supresi\u00f3n por parte del interesado en los supuestos en los que proceda.<\/p>\n<p>\u200b<\/p>\n<p><strong>Legitimaci\u00f3n \u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/strong><\/p>\n<p>\u200b<\/p>\n<p>La base legal para el tratamiento de los datos personales de los usuarios es la relaci\u00f3n contractual y el propio consentimiento del interesado.<\/p>\n<p>Asimismo, la oferta prospectiva de servicios est\u00e1 basada en el consentimiento que se solicita al usuario sin que ning\u00fan caso la retirada de este consentimiento condicione la ejecuci\u00f3n de otras finalidades.<\/p>\n<p><strong>Destinatarios \u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/strong><\/p>\n<p>\u200b<\/p>\n<p>Los datos que se recogen en esta web mediante los formularios correspondientes ser\u00e1n objeto de comunicaci\u00f3n a otras empresas que ejercen de encargados del tratamiento de datos personales, y que solo tratar\u00e1n los datos conforme a las estrictas indicaciones que REVYROD establece con dichos encargados. En todo caso los datos ser\u00e1n comunicados dentro del espacio de la Uni\u00f3n Europea y solo para los fines anteriormente indicados. En el marco de las comunicaciones indicadas en el p\u00e1rrafo anterior, se podr\u00e1n realizar transferencias internacionales de datos a terceros pa\u00edses u organizaciones internacionales, sobre los que exista una decisi\u00f3n de adecuaci\u00f3n de la Comisi\u00f3n Europea respecto a los mismos.<\/p>\n<p>\u200b<\/p>\n<p><strong>Derechos \u00bfCu\u00e1les son sus derechos cuando nos facilita sus datos?<\/strong><\/p>\n<p>\u200b<\/p>\n<p>A los usuarios de la web titularidad de REVYROD se les garantiza los derechos que se establecen en la legislaci\u00f3n en materia de Protecci\u00f3n de Datos Personales:<\/p>\n<p>En primer lugar, el usuario tiene derecho a obtener una confirmaci\u00f3n sobre si en REVYROD se est\u00e1n tratando datos personales que le conciernan o no.<\/p>\n<p>Los usuarios tendr\u00e1n derecho a acceder a sus datos personales, as\u00ed como a solicitar la rectificaci\u00f3n de los datos que sean inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines que fueron recogidos.<\/p>\n<p>Los usuarios tienen derecho a oponerse al tratamiento de sus datos personales, por lo que REVYROD dejar\u00e1 de tratar sus datos, salvo si existen motivos leg\u00edtimos, imperiosos, o el ejercicio o la defensa de posibles reclamaciones.<\/p>\n<p>Los usuarios tienen la facultad de solicitar a REVYROD que limite los tratamientos de sus datos personales cuando se cumplan los requisitos que el Reglamento UE 2016\/679 exige.<\/p>\n<p>Los usuarios tienen derecho a recibir en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica los datos personales que le incumban y que haya facilitado a REVYROD, o solicitar a la REVYROD que los transmita directamente a otro responsable cuando sea t\u00e9cnicamente posible.<\/p>\n<p>Por \u00faltimo, informamos que cualquier interesado podr\u00e1 presentar una reclamaci\u00f3n ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, especialmente cuando no haya obtenido satisfacci\u00f3n en el ejercicio de sus derechos.<\/p>\n<p>REVYROD informa al usuario de las finalidades para las que emplear\u00e1 los datos personales recabados en esta Web en los diversos formularios:<\/p>\n<p>\u200b<\/p>\n<p><strong>3.1.) Formulario de Contacto.<\/strong><\/p>\n<p>\u200b<\/p>\n<p>REVYROD, le informa que su direcci\u00f3n de correo electr\u00f3nico ser\u00e1 introducida en un fichero automatizado (correo electr\u00f3nico) con la finalidad de proporcionarles informaci\u00f3n de nuestros servicios y proyectos o cualquier otra informaci\u00f3n que se nos solicite por e-mail. De conformidad con lo establecido en los p\u00e1rrafos anteriores REVYROD se compromete a no ceder, comunicar, ni compartir los datos con terceros sin su aprobaci\u00f3n expresa. Asimismo, REVYROD cancelar\u00e1 o rectificar\u00e1 los datos cuando resulten inexactos, incompletos o hayan dejado de ser necesarios o pertinentes para su finalidad, de conformidad con lo previsto en el Reglamento UE 2016\/679 Europeo de Protecci\u00f3n de Datos y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y Garant\u00eda de los Derechos Digitales.<\/p>\n<p><strong>3.2.) Inscripci\u00f3n lista de distribuci\u00f3n ofertas y promociones.<\/strong><\/p>\n<p>\u200b<\/p>\n<p>REVYROD le informa que su direcci\u00f3n de correo electr\u00f3nico ser\u00e1 introducida en un fichero automatizado (lista de distribuci\u00f3n) con la finalidad de proporcionarles informaci\u00f3n de nuestras noticias y ofertas por e-mail. De conformidad con lo establecido en los p\u00e1rrafos anteriores REVYROD se compromete a no ceder, vender, ni compartir los datos con terceros sin su aprobaci\u00f3n expresa. Asimismo, REVYROD cancelar\u00e1 o rectificar\u00e1 los datos cuando resulten inexactos, incompletos o hayan dejado de ser necesarios o pertinentes para su finalidad, de conformidad con lo previsto en la normativa vigente en protecci\u00f3n de datos. El Usuario podr\u00e1 revocar el consentimiento prestado y ejercer los derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n, oposici\u00f3n, limitaci\u00f3n, supresi\u00f3n y portabilidad dirigi\u00e9ndose a tal efecto a la direcci\u00f3n abajo indicada, identific\u00e1ndose debidamente e indicando de forma visible el concreto derecho que se ejerce, en la propia web o a trav\u00e9s de correo.<\/p>\n<p>REVYROD adopta los niveles de seguridad correspondientes requeridos por el Reglamento de Medidas de Seguridad aprobado por el Real Decreto 1720\/2007, de 21 de diciembre. No obstante, REVYROD no asume ninguna responsabilidad por los da\u00f1os y perjuicios derivados de alteraciones que terceros pueden causar en los sistemas inform\u00e1ticos, documentos electr\u00f3nicos o ficheros del usuario. REVYROD podr\u00e1 utilizar \u201ccookies\u201d durante la prestaci\u00f3n de servicios del sitio web. Los \u201ccookies\u201d son ficheros f\u00edsicos de informaci\u00f3n personal alojados en el propio Terminal del usuario. El usuario tiene la posibilidad de configurar su programa navegador de manera que se impida la creaci\u00f3n de archivos cookie o se advierta de la misma.<\/p>\n<p>Nuestra pol\u00edtica con respecto al correo electr\u00f3nico se centra en remitir \u00fanicamente comunicaciones que usted haya consentido recibir. Si prefiere no recibir estos mensajes por correo electr\u00f3nico le ofreceremos a trav\u00e9s de los mismos la posibilidad de ejercer su derecho de cancelaci\u00f3n y renuncia a la recepci\u00f3n de estos mensajes, en conformidad con lo dispuesto en el Art. 22 de la Ley 34\/2002 de Servicios para la Sociedad de la Informaci\u00f3n y de Comercio electr\u00f3nico (LSSICE).<\/p>\n<p>\u200b<\/p>\n<p><strong>4. Procedimiento en caso de realizaci\u00f3n de actividades de car\u00e1cter il\u00edcito<\/strong><\/p>\n<p>\u200b<\/p>\n<p>En el caso de que cualquier usuario o un tercero considere que existen hechos o circunstancias que revelen el car\u00e1cter il\u00edcito de la utilizaci\u00f3n de cualquier contenido y\/o de la realizaci\u00f3n de cualquier actividad en las p\u00e1ginas Web incluidas o accesibles a trav\u00e9s del sitio Web, deber\u00e1 enviar una notificaci\u00f3n a REVYROD identific\u00e1ndose debidamente, especificando las supuestas infracciones y declarando expresamente y bajo su responsabilidad que la informaci\u00f3n proporcionada en la notificaci\u00f3n es exacta.<\/p>\n<p>\u200b<\/p>\n<p><strong>5. Datos de Contacto<\/strong><\/p>\n<p>\u200b<\/p>\n<p>Todas las notificaciones y comunicaciones entre los usuarios y REVYROD se considerar\u00e1n eficaces, a todos los efectos, cuando se realicen a trav\u00e9s de correo postal o correo electr\u00f3nico o comunicaci\u00f3n telef\u00f3nica.<\/p>\n<p>Los usuarios deber\u00e1n dirigirse a REVYROD mediante:<\/p>\n<p>a) Delegado de Protecci\u00f3n de Datos:<\/p>\n<p>b) Env\u00edo por correo postal a la siguiente direcci\u00f3n: C\/ Infanta Elena 16, Pol\u00edgono Industrial Cho, C.P. 38632, Arona, Santa Cruz de Tenerife.<\/p>\n<p>C) Env\u00edo por correo electr\u00f3nico a la siguiente direcci\u00f3n:<\/p>\n<p>\u200b<\/p>\n<p><strong>6. Modificaci\u00f3n y actualizaci\u00f3n de la pol\u00edtica<\/strong><\/p>\n<p>\u200b<\/p>\n<p>La presente pol\u00edtica podr\u00e1 ser modificada en cualquier momento, siendo debidamente publicada en este mismo sitio, por causa de cambio de requisitos legales, cambios jurisprudenciales y, en general, por cambios en la actuaci\u00f3n y estrategia de REVYROD. La publicaci\u00f3n y acceso por parte de los usuarios, ser\u00e1 realizada a trav\u00e9s de este mismo sitio, entendi\u00e9ndose que las relaciones establecidas con los mismos, con anterioridad al cambio, se regir\u00e1n por las normas previstas en el momento en que se accedi\u00f3 al sitio Web para su establecimiento.<\/p>\n<h4>Grupo Revyrod S.L<\/h4>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading source=\"post_title\" use_theme_fonts=\"yes\"]ENTIDAD: REVYROD, S.L. \u200bC.I.F : B38421525 \u200bC\/Infanta Elena 16 \u2013 Poligono Industrial Cho \u2013 38632 \u2013 Arona \u2013 Santa Cruz de Tenerife gourmetlandtfe@gmail.com\/info@gourmetland.net +34 922 79 84 89 \u200b 1. Objeto y aceptaci\u00f3n \u200b El presente aviso legal regula el uso del sitio Web:\u00a0www.gourmetland.net.\u00a0La navegaci\u00f3n por la p\u00e1gina\u00a0www.gourmetland.net\u00a0atribuye la condici\u00f3n de usuario de...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v26.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de Privacidad - La Brasserie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labrasserie.es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/labrasserie.es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"La Brasserie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/\",\"url\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de Privacidad - La Brasserie\",\"isPartOf\":{\"@id\":\"https:\/\/labrasserie.es\/#website\"},\"datePublished\":\"2022-12-15T15:55:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/labrasserie.es\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/labrasserie.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/labrasserie.es\/#website\",\"url\":\"https:\/\/labrasserie.es\/\",\"name\":\"La Brasserie\",\"description\":\"Restaurante italiano en Adeje\",\"publisher\":{\"@id\":\"https:\/\/labrasserie.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/labrasserie.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/labrasserie.es\/#organization\",\"name\":\"La Brasserie\",\"url\":\"https:\/\/labrasserie.es\/\",\"logo\":{\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-organization-logo\"},\"address\":{\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"28.084939299457616\",\"longitude\":\"-16.735988369667357\"},\"telephone\":[],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"922718024\",\"email\":\"info@labrasserie.es\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"13:00\",\"closes\":\"23:00\"}],\"areaServed\":\"Tenerife\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-place-address\",\"streetAddress\":\"CC. Litoral, C. Londres, Loc. 204, 38660 Playa, Santa Cruz de Tenerife\",\"addressLocality\":\"Costa Adeje\",\"postalCode\":\"38660\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-organization-logo\",\"url\":\"https:\/\/labrasserie.es\/wp-content\/uploads\/2023\/05\/brasserie.png\",\"contentUrl\":\"https:\/\/labrasserie.es\/wp-content\/uploads\/2023\/05\/brasserie.png\",\"width\":350,\"height\":350,\"caption\":\"La Brasserie\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Costa Adeje\" \/>\n<meta name=\"geo.position\" content=\"28.084939299457616;-16.735988369667357\" \/>\n<meta name=\"geo.region\" content=\"Espa\u00f1a\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad - La Brasserie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labrasserie.es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Privacidad","og_url":"https:\/\/labrasserie.es\/politica-de-privacidad\/","og_site_name":"La Brasserie","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/","url":"https:\/\/labrasserie.es\/politica-de-privacidad\/","name":"Pol\u00edtica de Privacidad - La Brasserie","isPartOf":{"@id":"https:\/\/labrasserie.es\/#website"},"datePublished":"2022-12-15T15:55:44+00:00","breadcrumb":{"@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/labrasserie.es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/labrasserie.es\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/labrasserie.es\/#website","url":"https:\/\/labrasserie.es\/","name":"La Brasserie","description":"Restaurante italiano en Adeje","publisher":{"@id":"https:\/\/labrasserie.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labrasserie.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place"],"@id":"https:\/\/labrasserie.es\/#organization","name":"La Brasserie","url":"https:\/\/labrasserie.es\/","logo":{"@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-organization-logo"},"image":{"@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-organization-logo"},"address":{"@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"28.084939299457616","longitude":"-16.735988369667357"},"telephone":[],"contactPoint":{"@type":"ContactPoint","telephone":"922718024","email":"info@labrasserie.es"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"13:00","closes":"23:00"}],"areaServed":"Tenerife"},{"@type":"PostalAddress","@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-place-address","streetAddress":"CC. Litoral, C. Londres, Loc. 204, 38660 Playa, Santa Cruz de Tenerife","addressLocality":"Costa Adeje","postalCode":"38660","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/labrasserie.es\/politica-de-privacidad\/#local-main-organization-logo","url":"https:\/\/labrasserie.es\/wp-content\/uploads\/2023\/05\/brasserie.png","contentUrl":"https:\/\/labrasserie.es\/wp-content\/uploads\/2023\/05\/brasserie.png","width":350,"height":350,"caption":"La Brasserie"}]},"geo.placename":"Costa Adeje","geo.position":{"lat":"28.084939299457616","long":"-16.735988369667357"},"geo.region":"Espa\u00f1a"},"_links":{"self":[{"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":1,"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":16,"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/pages\/15\/revisions\/16"}],"wp:attachment":[{"href":"https:\/\/labrasserie.es\/es\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}